{"id":9360,"date":"2019-01-03T13:07:24","date_gmt":"2019-01-03T12:07:24","guid":{"rendered":"http:\/\/boxcommunication.it\/web\/?p=9360"},"modified":"2020-01-21T23:40:15","modified_gmt":"2020-01-21T23:40:15","slug":"programmi-tv-radio-fm-sono-out-e-quando-spotify-diventa-illegale","status":"publish","type":"post","link":"https:\/\/boxcommunication.it\/web\/programmi-tv-radio-fm-sono-out-e-quando-spotify-diventa-illegale\/","title":{"rendered":"Quando programmi tv e radio fm sono out. E quando Spotify diventa illegale"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p>Durante la spesa settimane, in pausa pranzo o mentre corriamo sul tapis roulant: <strong>in ogni spazio della nostra quotidianit&agrave; siamo costantemente accompagnati da un sottofondo musicale.<\/strong><br>\nPotrebbe essere piacevole, di certo, se non ci fosse un piccolo ingrediente: la mancanza di definzioone. Per chi sceglie la filodiffusione nella propria attivit&agrave; commerciale la scelta di un emittente radio o tv&nbsp;<strong>pu&ograve; sembrare un plus, un aggiunta all&rsquo;esperienza d&rsquo;acquisto dell&rsquo;utente<\/strong>. Non sempre per&ograve; il risultato &egrave; positivo: molto spesso anzi, ci si trova alle prese con un <strong>arma a doppio taglio.<\/strong><\/p>\n<p><strong>Se per risparmiare si sceglie di non assoldare un professionista i rischi sono alti.<\/strong> I music provider (decine e decine in Italia, riuniti nell&rsquo;associaizone AMP) che offrono un servizio a pagamento sono in grado<br>\ndi <strong>definire un disegno musicale ad hoc e spot radiofonici o video sui servizi offerti dalla vostra attivit&agrave;.<\/strong> Si aggiungono anche <strong>altri costi certo, quelli di SIAE e SCF,<\/strong> che vanno corrisposti in ogni occasione di diffusione audio e video in luogo pubblico.<br>\nInsomma, volendo risparmiare non si pensa certo di affidarsi ad un music provider che offre un servizio pagamento, certo. <strong>Ma quanto costa in realt&agrave; scegliere un servizio gratuito?<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9363 alignleft\" src=\"http:\/\/boxcommunication.it\/web\/wp-content\/uploads\/2020\/01\/download.jpg\" alt=\"tv in luogo pubblico \" width=\"291\" height=\"173\"><\/p>\n<p>Diffondere radio o tv pubbliche significa<strong> non scegliere i contenuti, e, rischio con alta incidenza, trasmettere la pubblicit&agrave; di potenziali concorrenti. Un costo forse assai pi&ugrave; alto del servizio dedicato.<\/strong><br>\nE anche per i borderliner che hanno usato <strong>Spotify<\/strong> finora c&rsquo;&egrave; ormai poco scampo: <strong>le condizioni d&rsquo;uso del servizio che vi fa creare la vostra playlist del cuore mette in chiaro che l&rsquo;uso &egrave; privato.&nbsp;<\/strong>Spotify premium o free sono servizi dedicati <strong>esclusivamente all&rsquo;ascolto personale o casalingo<\/strong>. Non si scappa.<\/p>\n<p>Conviene, a conti fatti, affidarsi ad un servizio di diffusione che non &egrave; stato creato apposta per voi? Ragionandoci, <strong>sarebbe come eliminare il lavoro di chi cura l&rsquo;illuminazione o l&rsquo;allestimento del punto vendita. Immaginate i risultati?<\/strong><\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"<p>Durante la spesa settimane, in pausa pranzo o mentre corriamo sul tapis roulant: in ogni spazio della nostra quotidianit&agrave; siamo costantemente accompagnati da un sottofondo musicale. Potrebbe essere piacevole, di certo, se non ci fosse un piccolo ingrediente: la mancanza di definzioone. Per chi sceglie la filodiffusione nella propria attivit&agrave; commerciale la scelta di un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10187,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[17,10],"class_list":["post-9360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-servizio-radio","tag-siae"],"_links":{"self":[{"href":"https:\/\/boxcommunication.it\/web\/wp-json\/wp\/v2\/posts\/9360"}],"collection":[{"href":"https:\/\/boxcommunication.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boxcommunication.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boxcommunication.it\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/boxcommunication.it\/web\/wp-json\/wp\/v2\/comments?post=9360"}],"version-history":[{"count":2,"href":"https:\/\/boxcommunication.it\/web\/wp-json\/wp\/v2\/posts\/9360\/revisions"}],"predecessor-version":[{"id":10181,"href":"https:\/\/boxcommunication.it\/web\/wp-json\/wp\/v2\/posts\/9360\/revisions\/10181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boxcommunication.it\/web\/wp-json\/wp\/v2\/media\/10187"}],"wp:attachment":[{"href":"https:\/\/boxcommunication.it\/web\/wp-json\/wp\/v2\/media?parent=9360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boxcommunication.it\/web\/wp-json\/wp\/v2\/categories?post=9360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boxcommunication.it\/web\/wp-json\/wp\/v2\/tags?post=9360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}